{"id":13,"date":"2023-03-06T18:33:12","date_gmt":"2023-03-06T10:33:12","guid":{"rendered":"https:\/\/brudeze.com\/?page_id=13"},"modified":"2023-03-28T19:53:23","modified_gmt":"2023-03-28T11:53:23","slug":"feedback","status":"publish","type":"page","link":"https:\/\/brudeze.com\/es\/feedback","title":{"rendered":"FEEDBACK\/INQUIRY"},"content":{"rendered":"<div class=\"wpcf7 no-js\" id=\"wpcf7-f98-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"98\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/13#wpcf7-f98-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/13#wpcf7-f98-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"98\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f98-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-xs-12 col-sm-12 col-md-12\">\n\t\t<p>Name:<span class=\"wpcf7-form-control-wrap\" data-name=\"my_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"my_name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12 col-sm-12 col-md-12\">\n\t\t<p>Email:<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12 col-sm-12 col-md-12\">\n\t\t<p>Phone:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel form-control\" aria-invalid=\"false\" placeholder=\"Your Phone\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12 col-sm-12 col-md-12\">\n\t\t<p>Content:<span class=\"wpcf7-form-control-wrap\" data-name=\"my_content\"><textarea cols=\"40\" rows=\"3\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" placeholder=\"Content\" name=\"my_content\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-272\"><label><span class=\"wpcf7-quiz-label\">9+8=?(Write the answer)<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-272\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-272\" value=\"f6e582ba21392e8bb9baf847cfa7cf72\" \/><\/span>\n<\/p>\n<div class=\"col-xs-12 col-md-12 butt_in\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n\t<\/p>\n<\/div>\n<style>\n.wpcf7-form input[type=\"submit\"] {\n font: normal 14px \/ 16px \"Open Sans\",Helvetica,Arial,Verdana,sans-serif;\n text-transform: none;\n -webkit-border-radius: 5px;\n border-radius: 5px;\n padding: 12px 18px 11px 18px;\n min-height: 38px;\n line-height: 38px;\n padding-top: 0;\n padding-bottom: 0;\n\tcolor: #fff;\n background-color: #0c4d89;\n background: #0c4d89;\n\tborder:0;\n}\n.wpcf7-not-valid-tip {color:red}\n<\/style><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":3,"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":322,"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/pages\/13\/revisions\/322"}],"wp:attachment":[{"href":"https:\/\/brudeze.com\/es\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}